{"id":1694,"date":"2016-06-17T10:32:30","date_gmt":"2016-06-17T09:32:30","guid":{"rendered":"http:\/\/fh-waltrop.de\/?p=1694"},"modified":"2016-06-17T10:32:30","modified_gmt":"2016-06-17T09:32:30","slug":"caritas-verscharfungen-im-asylrecht-setzen-falsche-signale","status":"publish","type":"post","link":"https:\/\/fh-waltrop.de\/index.php\/caritas-verscharfungen-im-asylrecht-setzen-falsche-signale\/","title":{"rendered":"Caritas: Versch\u00e4rfungen im Asylrecht setzen falsche Signale"},"content":{"rendered":"<figure id=\"attachment_398\" aria-describedby=\"caption-attachment-398\" style=\"width: 900px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/fh-waltrop.de\/wp-content\/uploads\/2015\/10\/ueberfahrt.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"398\" data-permalink=\"https:\/\/fh-waltrop.de\/index.php\/integration-point-in-dortmund-soll-fluchtlinge-schneller-in-den-arbeitsmarkt-bringen\/boot\/\" data-orig-file=\"https:\/\/fh-waltrop.de\/wp-content\/uploads\/2015\/10\/ueberfahrt.jpg\" data-orig-size=\"900,216\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Bernd Schaefer&quot;,&quot;camera&quot;:&quot;Nikon SUPER COOLSCAN 5000 ED&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1257771766&quot;,&quot;copyright&quot;:&quot;Copyright by Bernd Schaefer&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;Boot&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Boot\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Foto (c): B. Sch\u00e4fer&lt;\/p&gt;\n\" data-large-file=\"https:\/\/fh-waltrop.de\/wp-content\/uploads\/2015\/10\/ueberfahrt.jpg\" class=\"size-full wp-image-398\" src=\"http:\/\/fh-waltrop.de\/wp-content\/uploads\/2015\/10\/ueberfahrt.jpg\" alt=\"Foto (c): B. Sch\u00e4fer\" width=\"900\" height=\"216\" srcset=\"https:\/\/fh-waltrop.de\/wp-content\/uploads\/2015\/10\/ueberfahrt.jpg 900w, https:\/\/fh-waltrop.de\/wp-content\/uploads\/2015\/10\/ueberfahrt-300x72.jpg 300w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><figcaption id=\"caption-attachment-398\" class=\"wp-caption-text\">Foto (c): B. Sch\u00e4fer<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><b>Berlin, 17. Juni 2016. <\/b>\u201eEs ist richtig, dass der Bundesrat die Abstimmung zum Gesetz der sicheren Herkunftsstaaten vertagt hat. So kann das\u00a0Gesetz nochmals kritisch diskutiert werden. Wenn Tunesien, Marokko und Algerien zu sicheren Herkunftsl\u00e4ndern erkl\u00e4rt werden, besteht die Gefahr, dass das Ergebnis eines individuellen Asylpr\u00fcfverfahrens vorweggenommen wird\u201c, so Caritas-Pr\u00e4sident Peter Neher. Verfolgten aus diesen L\u00e4ndern drohe dann die Abschiebung, weil ihre Situation im beschleunigten Verfahren h\u00e4ufig nicht erkannt werde. Fraglich sei, inwiefern die vom Bundesverfassungsgericht gesetzten Mindestanforderungen zur Einstufung von sicheren Herkunftsstaaten \u00fcberhaupt erf\u00fcllt seien. \u201eDas Ziel, die Asylverfahren in Deutschland zu beschleunigen, darf nicht \u00fcber die Belange schutzbed\u00fcrftiger Menschen gestellt werden\u201c, so Neher.<\/p>\n<p style=\"text-align: justify;\">Auch beim geplanten Integrationsgesetz muss dringend nachgebessert werden. \u201eDas Gesetz ist h\u00f6chst widerspr\u00fcchlich. Die geplanten Regelungen zum Spracherwerb sowie zur Arbeitsmarktintegration von Asylsuchenden und Geduldeten stellen wesentliche Verbesserungen dar und werden die Integration erleichtern\u201c, so Neher. \u201eAndere Teile des Gesetzes zielen aber auf Abschreckung und bauen neue H\u00fcrden auf\u201c, kritisiert Neher. Anerkannte Fl\u00fcchtlinge sollen k\u00fcnftig nach drei Jahren nur dann eine unbefristete Aufenthaltserlaubnis erhalten, wenn sie ihren Lebensunterhalt selbst sichern k\u00f6nnen und \u00fcber sehr gute Sprachkenntnisse verf\u00fcgen. \u201eViele Gefl\u00fcchtete arbeiten zun\u00e4chst als ungelernte Kr\u00e4fte im Niedriglohnsektor. So ist es nicht verwunderlich, dass sie nicht immer ohne Unterst\u00fctzung f\u00fcr sich und ihre Familie aufkommen k\u00f6nnen\u201c, verdeutlicht Neher. Bisher wurde anerkannten Fl\u00fcchtlingen eine dauerhafte Schutzzusage und Bleibeperspektive gegeben. \u201eAn dieser Regelung m\u00fcssen wir auch weiterhin festhalten. Nur so kann die besondere Situation von Fl\u00fcchtlingen ber\u00fccksichtigt werden\u201c, so Neher.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berlin, 17. Juni 2016. \u201eEs ist richtig, dass der Bundesrat die Abstimmung zum Gesetz der sicheren Herkunftsstaaten vertagt hat. So kann das\u00a0Gesetz nochmals kritisch diskutiert werden. Wenn Tunesien, Marokko und Algerien zu sicheren Herkunftsl\u00e4ndern erkl\u00e4rt werden, besteht die Gefahr, dass das Ergebnis eines individuellen Asylpr\u00fcfverfahrens vorweggenommen wird\u201c, so Caritas-Pr\u00e4sident Peter Neher. Verfolgten aus diesen L\u00e4ndern [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,3],"tags":[],"class_list":{"0":"post-1694","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-aus-aller-welt","7":"category-news","8":"entry"},"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pdR32e-rk","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/posts\/1694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/comments?post=1694"}],"version-history":[{"count":0,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/posts\/1694\/revisions"}],"wp:attachment":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/media?parent=1694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/categories?post=1694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/tags?post=1694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}