{"id":1706,"date":"2016-06-17T21:14:24","date_gmt":"2016-06-17T20:14:24","guid":{"rendered":"http:\/\/fh-waltrop.de\/?p=1706"},"modified":"2016-06-17T21:15:13","modified_gmt":"2016-06-17T20:15:13","slug":"menschlichkeit-wird-bestraft","status":"publish","type":"post","link":"https:\/\/fh-waltrop.de\/index.php\/menschlichkeit-wird-bestraft\/","title":{"rendered":"Menschlichkeit wird bestraft"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/fh-waltrop.de\/wp-content\/uploads\/2016\/05\/Fluechtlingsrat-NRW.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1520\" data-permalink=\"https:\/\/fh-waltrop.de\/index.php\/stellenausschreibung-referentin-vernetzung-ehrenamt\/fluechtlingsrat-nrw\/\" data-orig-file=\"https:\/\/fh-waltrop.de\/wp-content\/uploads\/2016\/05\/Fluechtlingsrat-NRW.jpg\" data-orig-size=\"587,170\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Fluechtlingsrat NRW\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/fh-waltrop.de\/wp-content\/uploads\/2016\/05\/Fluechtlingsrat-NRW.jpg\" class=\"alignnone size-full wp-image-1520\" src=\"http:\/\/fh-waltrop.de\/wp-content\/uploads\/2016\/05\/Fluechtlingsrat-NRW.jpg\" alt=\"Fluechtlingsrat NRW\" width=\"587\" height=\"170\" srcset=\"https:\/\/fh-waltrop.de\/wp-content\/uploads\/2016\/05\/Fluechtlingsrat-NRW.jpg 587w, https:\/\/fh-waltrop.de\/wp-content\/uploads\/2016\/05\/Fluechtlingsrat-NRW-300x87.jpg 300w\" sizes=\"auto, (max-width: 587px) 100vw, 587px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Der Fl\u00fcchtlingsrat NRW h\u00e4lt den Entwurf des neuen Integrationsgesetzes f\u00fcr\u00a0ein verheerendes Signal an engagierte B\u00fcrger \u2013\u00a0<\/strong>\u00a0<strong>\u00fcber 20.000 B\u00fcrgen in Deutschland drohen extrem hohe finanzielle Belastungen, nicht wenigen der finanzielle Ruin.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Nach Auffassung des Fl\u00fcchtlingsrats bestraft das neue Integrationsgesetz diejenigen, die sich f\u00fcr syrische Fl\u00fcchtlinge besonders eingesetzt haben. Es geht um die langen Laufzeiten der Verpflichtungserkl\u00e4rungen f\u00fcr die legale Einreise von syrischen Kontingent-Fl\u00fcchtlingen \u00fcber die Bundes- und Landesprogramme sowie die R\u00fcckforderungen des Staates von den engagierten B\u00fcrgen.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00dcber 20.000 B\u00fcrgen in Deutschland sollen laut Gesetzentwurf volle f\u00fcnf Jahre f\u00fcr die Lebenshaltungskosten der legal eingereisten Gefl\u00fcchteten aufkommen. Die B\u00fcrgen haben durch ihre Unterschrift einer so genannten Verpflichtungserkl\u00e4rung ein gro\u00dfes finanzielles und rechtliches Risiko auf sich genommen. Die Verpflichtungsgeber in Nordrhein-Westfalen sind davon ausgegangen, dass ihre pers\u00f6nliche Verpflichtung und finanzielle Belastung endet, wenn die eingereisten Personen als Fl\u00fcchtlinge anerkannt werden: \u201eMit der Titelerteilung nach erfolgreichem Asylverfahren wird der neue Aufenthaltszweck aufenthaltsrechtlich anerkannt, so dass die Geltung einer im Zusammenhang mit der Landesaufnahmeanordnung abgegebenen Verpflichtungserkl\u00e4rung endet\u201c (Erlass des NRW-Innenministers J\u00e4ger, 24. April 2015). Das Land NRW vertritt somit eine andere Meinung als Bundesinnenminister de Maizi\u00e8re, der auf eine Fortgeltung der Verpflichtungserkl\u00e4rung trotz Fl\u00fcchtlingsanerkennung besteht.<\/p>\n<p style=\"text-align: justify;\"><strong>Gef\u00e4hrliche Flucht verhindert, vom Staat bestraft und ruiniert<\/strong><\/p>\n<p style=\"text-align: justify;\">Die Programme f\u00fcr Kontingentfl\u00fcchtlinge bieten eine der wenigen legalen und sicheren Einreiseformen nach Deutschland und entziehen den Schleppern ihre illegale Gesch\u00e4ftsgrundlage. Gleichzeitig findet in vorbildlicher Weise eine Integration statt. Denn durch die B\u00fcrgen erhalten die Gefl\u00fcchteten Unterst\u00fctzung bei Amtsg\u00e4ngen, der Schulanmeldung, dem Spracherwerb und der Arbeitssuche. Auch hierdurch entlasten die Verpflichtungsgeber Bund, L\u00e4nder und Kommunen.<\/p>\n<p style=\"text-align: justify;\">Tritt das neue Integrationsgesetz mit der derzeit vorgesehenen Passage zur Geltung der Verpflichtungserkl\u00e4rungen in Kraft, werden die B\u00fcrgen f\u00fcr ihr au\u00dferordentliches Engagement abgestraft. Sollten die Jobcenter beginnen, von den B\u00fcrgen die an die Gefl\u00fcchteten nach ihrer Asylanerkennung gezahlten Sozialleistungen zur\u00fcckzufordern, m\u00fcssen die Verpflichtungsgeber mit R\u00fcckzahlungen in H\u00f6he von 300 bis 550 Euro pro Person und Monat rechnen. Da einige B\u00fcrgen sogar mehrere Verpflichtungserkl\u00e4rungen unterzeichnet haben, droht diesen der finanzielle Ruin. Eine syrisch-st\u00e4mmige Verpflichtungsgeberin in Bad Godesberg, mit deren Hilfe sieben Familienangeh\u00f6rige in Deutschland Sicherheit finden konnten, muss sich auf eine R\u00fcckforderung des Staates in H\u00f6he von bis zu 210.000 Euro einstellen.<\/p>\n<p style=\"text-align: justify;\">Der Fl\u00fcchtlingsrat fordert deshalb ein Erl\u00f6schen der Verpflichtungserkl\u00e4rung nach\u00a0einem\u00a0Jahr oder bei Fl\u00fcchtlingsanerkennung.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Fl\u00fcchtlingsrat NRW h\u00e4lt den Entwurf des neuen Integrationsgesetzes f\u00fcr\u00a0ein verheerendes Signal an engagierte B\u00fcrger \u2013\u00a0\u00a0\u00fcber 20.000 B\u00fcrgen in Deutschland drohen extrem hohe finanzielle Belastungen, nicht wenigen der finanzielle Ruin. Nach Auffassung des Fl\u00fcchtlingsrats bestraft das neue Integrationsgesetz diejenigen, die sich f\u00fcr syrische Fl\u00fcchtlinge besonders eingesetzt haben. Es geht um die langen Laufzeiten der Verpflichtungserkl\u00e4rungen [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,3],"tags":[],"class_list":{"0":"post-1706","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-aus-aller-welt","7":"category-news","8":"entry"},"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pdR32e-rw","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/posts\/1706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/comments?post=1706"}],"version-history":[{"count":0,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/posts\/1706\/revisions"}],"wp:attachment":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/media?parent=1706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/categories?post=1706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/tags?post=1706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}