{"id":2797,"date":"2017-07-23T16:28:04","date_gmt":"2017-07-23T15:28:04","guid":{"rendered":"http:\/\/fh-waltrop.de\/?p=2797"},"modified":"2017-07-25T10:35:32","modified_gmt":"2017-07-25T09:35:32","slug":"was-ist-zukunft-4","status":"publish","type":"post","link":"https:\/\/fh-waltrop.de\/index.php\/was-ist-zukunft-4\/","title":{"rendered":"Was ist Zukunft?"},"content":{"rendered":"<figure id=\"attachment_2699\" aria-describedby=\"caption-attachment-2699\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2699\" data-permalink=\"https:\/\/fh-waltrop.de\/index.php\/was-ist-zukunft-3\/was-ist-zukunft-3\/\" data-orig-file=\"https:\/\/fh-waltrop.de\/wp-content\/uploads\/2017\/06\/Was_ist_Zukunft_copyright_by_B_Schaefer.jpg\" data-orig-size=\"2657,1780\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Bernd Schaefer&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1471124231&quot;,&quot;copyright&quot;:&quot;Copyright by Bernd Schaefer&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;Was ist Zukunft?&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Was ist Zukunft?\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/fh-waltrop.de\/wp-content\/uploads\/2017\/06\/Was_ist_Zukunft_copyright_by_B_Schaefer-1024x686.jpg\" class=\"wp-image-2699 size-large\" src=\"http:\/\/fh-waltrop.de\/wp-content\/uploads\/2017\/06\/Was_ist_Zukunft_copyright_by_B_Schaefer-1024x686.jpg\" alt=\"\" width=\"1024\" height=\"686\" srcset=\"https:\/\/fh-waltrop.de\/wp-content\/uploads\/2017\/06\/Was_ist_Zukunft_copyright_by_B_Schaefer-1024x686.jpg 1024w, https:\/\/fh-waltrop.de\/wp-content\/uploads\/2017\/06\/Was_ist_Zukunft_copyright_by_B_Schaefer-300x201.jpg 300w, https:\/\/fh-waltrop.de\/wp-content\/uploads\/2017\/06\/Was_ist_Zukunft_copyright_by_B_Schaefer-768x515.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-2699\" class=\"wp-caption-text\">Haben wir eine Zukunft? Foto (c): B. Sch\u00e4fer<\/figcaption><\/figure>\n<p>Unser Projekt &#8222;Was ist Zukunft?&#8220; \u00a0wird vom 24.07.2017 \u00a0bis zum 08.09.2017 im Waltroper Rathaus (M\u00fcnsterstr. 1) pr\u00e4sentiert.<\/p>\n<p>Zukunft ist Luxus,<\/p>\n<p>\u2022 wenn das Dach \u00fcber dem Kopf weggebombt wird,<\/p>\n<p>\u2022 nachts im \u00fcberf\u00fcllten Schlauchboot auf dem Meer,<\/p>\n<p>\u2022 beim Warten auf den Ausgang des Asylverfahrens.<\/p>\n<p>In diesen Situationen hat man das eigene Leben nicht mehr in der eigenen Hand.\u00a0Wie geht man in solchen, schier ausweglos erscheinenden, Situationen damit um?<\/p>\n<p>Die 19 in dem Projekt portr\u00e4tierten und interviewten Menschen haben darauf eine Antwort gefunden.\u00a0Flucht war eine ihrer Optionen, sich das Leben wieder anzueignen. Zuversicht die\u00a0andere, um neue Perspektiven zu schaffen. Daraus sind Handlungsr\u00e4ume\u00a0entstanden.<\/p>\n<p>Die auszugsweise wiedergegebenen Interviews, spiegeln dies. Zusammen ergeben\u00a0sie eine Narration des \u00dcberlebens.\u00a0Die Herkunftsl\u00e4nder der interviewten Menschen sind unterschiedlich. Sie\u00a0entsprechen den aktuellen Konfliktr\u00e4umen, wie sie durch die Presse bekannt sind:\u00a0West- und Nordafrika, Iran, Irak, Syrien, Libanon, Afghanistan.<\/p>\n<p>Das Projekt soll Auseinandersetzungen auf folgenden Ebenen erm\u00f6glichen:<\/p>\n<p>\u2022 die Fl\u00fcchtlinge werden der medialen Anonymit\u00e4t entrissen, sie erhalten Namen und\u00a0Gesicht,<\/p>\n<p>\u2022 sie leben jetzt hier, man kann ihnen helfen und sich mit ihnen und \u00fcber ihre\u00a0Geschichten auseinandersetzen,<\/p>\n<p>\u2022 es stellt sich zudem die Frage: Welche Zukunft wollen wir?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unser Projekt &#8222;Was ist Zukunft?&#8220; \u00a0wird vom 24.07.2017 \u00a0bis zum 08.09.2017 im Waltroper Rathaus (M\u00fcnsterstr. 1) pr\u00e4sentiert. Zukunft ist Luxus, \u2022 wenn das Dach \u00fcber dem Kopf weggebombt wird, \u2022 nachts im \u00fcberf\u00fcllten Schlauchboot auf dem Meer, \u2022 beim Warten auf den Ausgang des Asylverfahrens. In diesen Situationen hat man das eigene Leben nicht mehr [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3,6],"tags":[],"class_list":{"0":"post-2797","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-news","7":"category-waltrop-und-umgebung","8":"entry"},"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pdR32e-J7","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/posts\/2797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/comments?post=2797"}],"version-history":[{"count":0,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/posts\/2797\/revisions"}],"wp:attachment":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/media?parent=2797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/categories?post=2797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/tags?post=2797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}