{"id":2810,"date":"2017-07-26T11:18:32","date_gmt":"2017-07-26T10:18:32","guid":{"rendered":"http:\/\/fh-waltrop.de\/?p=2810"},"modified":"2017-08-01T10:58:25","modified_gmt":"2017-08-01T09:58:25","slug":"waltrop-hat-keinen-platz-fur-rassismus","status":"publish","type":"post","link":"https:\/\/fh-waltrop.de\/index.php\/waltrop-hat-keinen-platz-fur-rassismus\/","title":{"rendered":"&#8222;Waltrop hat keinen Platz f\u00fcr Rassismus&#8220;"},"content":{"rendered":"<figure id=\"attachment_2811\" aria-describedby=\"caption-attachment-2811\" style=\"width: 960px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2811\" data-permalink=\"https:\/\/fh-waltrop.de\/index.php\/waltrop-hat-keinen-platz-fur-rassismus\/wasistzukunfteroeffnungmitbm\/\" data-orig-file=\"https:\/\/fh-waltrop.de\/wp-content\/uploads\/2017\/07\/WasistZukunftEroeffnungmitBM.jpg\" data-orig-size=\"960,652\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WasistZukunftEroeffnungmitBM\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/fh-waltrop.de\/wp-content\/uploads\/2017\/07\/WasistZukunftEroeffnungmitBM.jpg\" class=\"wp-image-2811 size-full\" src=\"http:\/\/fh-waltrop.de\/wp-content\/uploads\/2017\/07\/WasistZukunftEroeffnungmitBM.jpg\" alt=\"\" width=\"960\" height=\"652\" srcset=\"https:\/\/fh-waltrop.de\/wp-content\/uploads\/2017\/07\/WasistZukunftEroeffnungmitBM.jpg 960w, https:\/\/fh-waltrop.de\/wp-content\/uploads\/2017\/07\/WasistZukunftEroeffnungmitBM-300x204.jpg 300w, https:\/\/fh-waltrop.de\/wp-content\/uploads\/2017\/07\/WasistZukunftEroeffnungmitBM-768x522.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><figcaption id=\"caption-attachment-2811\" class=\"wp-caption-text\">Foto: Hasan Ayad<\/figcaption><\/figure>\n<p>Ausstellungser\u00f6ffnung im Waltroper Rathaus mit B\u00fcrgermeisterin Nicole Moenikes (2vr), Gesamtschullehrerin Ina Otto, Karen Ayad, Sch\u00fclerin und Mitwirkende am Projekt &#8222;Was ist Zukunft?&#8220;, sowie\u00a0Bernd Sch\u00e4fer, Fotograf und Initiator der Projekte.<\/p>\n<p>Mit den Worten: &#8222;Waltrop hat keinen Platz f\u00fcr Rassismus&#8220; er\u00f6ffnete letzten Montag (24.07.2017) B\u00fcrgermeisterin Nicole Moenikes die Ausstellungen &#8222;Was ist Zukunft?&#8220; und &#8222;Mein Waltrop&#8220; und betonte die gute Zusammenarbeit der verschiedenen Akteure hinsichtlich der anstehenden Integrationsaufgaben.<\/p>\n<p>VertreterInnen der verschiedenen Ratsfraktionen, der Stadtverwaltung aber auch interessierte B\u00fcrgerInnen nahmen die Gelegenheit wahr, sich in die Ausstellungen einf\u00fchren zu lassen und verlie\u00dfen diese\u00a0sichtlich beeindruckt und nachdenklich.<\/p>\n<p>Beispielhaft zitieren wir\u00a0<a href=\"https:\/\/www.facebook.com\/uwe.paczkowski.14\" data-hovercard=\"\/ajax\/hovercard\/user.php?id=100000697714416&amp;extragetparams=%7B%22directed_target_id%22%3A0%7D\" data-hovercard-prefer-more-content-show=\"1\">Uwe Paczkowski<\/a>, einen Besucher der Ausstellung, der seine Gedanken\u00a0auf Facebook ver\u00f6ffentlichte:<\/p>\n<p><em>&#8222;Es ist eine interessante und nachdenkliche Ausstellung \u00fcber die Schicksale und Wege der Fl\u00fcchtlinge, die in Waltrop e<span class=\"text_exposed_show\">in neues zu Hause gefunden haben!<\/span><\/em><\/p>\n<p><em>Fl\u00fcchtlinge waren auch auf der Er\u00f6ffnungsfeier, und in pers\u00f6nlichen Gespr\u00e4chen erz\u00e4hlten sie von den Ereignissen, die Trauer, Ihren Erlebnissen und Ihren Hoffnungen und Ziele, f\u00fcr ein sicheres Leben in Frieden in Waltrop, es war f\u00fcr mich sehr bewegend und ich war den Tr\u00e4nen nahe.<\/em><\/p>\n<p><em>Mein besonderer Dank gilt Hasan, ein toller, tapferer junger Mann,\u00a0den ich kennengelernt habe und mit ihm ein l\u00e4ngeres Gespr\u00e4ch hatte,\u00a0der einen schweren Weg hatte und jetzt nach vorne schaut. HASAN Du wirst Deine Ziele erreichen, auch immer wieder mit unserer Unterst\u00fctzung!!!<\/em><\/p>\n<p><em>W\u00fcnsche Dir Hasan und Deiner Familie, sowie allen Fl\u00fcchtlingen\u00a0eine erfolgreiche Zukunft in Frieden.&#8220;<\/em><\/p>\n<p>Dem schlie\u00dfen wir uns an.<\/p>\n<p>Weitere Informationen zu den Projekten findet man hier:<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"cpsa5qyp1e\"><p><a href=\"https:\/\/fh-waltrop.de\/index.php\/was-ist-zukunft-4\/\">Was ist Zukunft?<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Was ist Zukunft?&#8220; &#8212; Fl\u00fcchtlingshilfe Waltrop\" src=\"https:\/\/fh-waltrop.de\/index.php\/was-ist-zukunft-4\/embed\/#?secret=GMRRv02HwC#?secret=cpsa5qyp1e\" data-secret=\"cpsa5qyp1e\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"UOn6vNuQDr\"><p><a href=\"https:\/\/fh-waltrop.de\/index.php\/mein-waltrop\/\">Mein Waltrop<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Mein Waltrop&#8220; &#8212; Fl\u00fcchtlingshilfe Waltrop\" src=\"https:\/\/fh-waltrop.de\/index.php\/mein-waltrop\/embed\/#?secret=AYjORsanJt#?secret=UOn6vNuQDr\" data-secret=\"UOn6vNuQDr\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ausstellungser\u00f6ffnung im Waltroper Rathaus mit B\u00fcrgermeisterin Nicole Moenikes (2vr), Gesamtschullehrerin Ina Otto, Karen Ayad, Sch\u00fclerin und Mitwirkende am Projekt &#8222;Was ist Zukunft?&#8220;, sowie\u00a0Bernd Sch\u00e4fer, Fotograf und Initiator der Projekte. Mit den Worten: &#8222;Waltrop hat keinen Platz f\u00fcr Rassismus&#8220; er\u00f6ffnete letzten Montag (24.07.2017) B\u00fcrgermeisterin Nicole Moenikes die Ausstellungen &#8222;Was ist Zukunft?&#8220; und &#8222;Mein Waltrop&#8220; und betonte [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3,6],"tags":[],"class_list":{"0":"post-2810","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-news","7":"category-waltrop-und-umgebung","8":"entry"},"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pdR32e-Jk","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/posts\/2810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/comments?post=2810"}],"version-history":[{"count":0,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/posts\/2810\/revisions"}],"wp:attachment":[{"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/media?parent=2810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/categories?post=2810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fh-waltrop.de\/index.php\/wp-json\/wp\/v2\/tags?post=2810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}